{"id":15879,"date":"2023-09-10T10:22:00","date_gmt":"2023-09-10T10:22:00","guid":{"rendered":"https:\/\/fashion-wall.de\/?page_id=15879"},"modified":"2023-09-29T16:27:42","modified_gmt":"2023-09-29T16:27:42","slug":"datenschutzerklarung","status":"publish","type":"page","link":"https:\/\/fashion-wall.de\/es\/datenschutzerklarung\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"15879\" class=\"elementor elementor-15879\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-54c1425b elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"54c1425b\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1dcc27e2\" data-id=\"1dcc27e2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3685131c elementor-section-boxed elementor-section-height-default elementor-section-height-default wd-section-disabled\" data-id=\"3685131c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-71bbe0ad\" data-id=\"71bbe0ad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a8bc019 elementor-widget elementor-widget-elementskit-heading\" data-id=\"2a8bc019\" data-element_type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper center   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Pol\u00edtica de privacidad<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a000c3 elementor-absolute elementor-widget elementor-widget-elementskit-heading\" data-id=\"43a000c3\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper    ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Pol\u00edtica de privacidad<\/h2><\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d9f8be elementor-widget__width-initial color-scheme-inherit text-left elementor-widget elementor-widget-text-editor\" data-id=\"0d9f8be\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 14-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><b>1. la protecci\u00f3n de datos de un vistazo<\/b><\/p>\n<p><b>Notas generales <\/b><br>\nLos siguientes avisos ofrecen una visi\u00f3n sencilla de lo que ocurre con sus datos personales cuando visita este sitio web. Por datos personales se entiende cualquier dato que permita identificarle personalmente. Si desea informaci\u00f3n detallada sobre el tema de la protecci\u00f3n de datos, consulte nuestra pol\u00edtica de privacidad que figura debajo de este texto.<\/p>\n<p><b>Recogida de datos en este sitio web<\/b><u><br>\n\u00bfQui\u00e9n es responsable de la recogida de datos en este sitio web?<\/u><span style=\"color: var(--wd-text-color); font-size: 14px;\"><br>\nEl tratamiento de datos en este sitio web lo lleva a cabo el operador del sitio web. Encontrar\u00e1 los datos de contacto del operador del sitio web en la secci\u00f3n \"Informaci\u00f3n sobre el responsable del tratamiento\" de esta declaraci\u00f3n de protecci\u00f3n de datos.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfC\u00f3mo recogemos sus datos?<\/span><br>\nPor un lado, sus datos se recogen cuando usted nos los facilita. Puede tratarse de datos que usted introduce en un formulario de contacto, por ejemplo. Otros datos son recogidos autom\u00e1ticamente o con su consentimiento por nuestros sistemas inform\u00e1ticos cuando visita el sitio web. Se trata principalmente de datos t\u00e9cnicos (por ejemplo, navegador de Internet, sistema operativo u hora de acceso a la p\u00e1gina). Estos datos se recogen autom\u00e1ticamente en cuanto usted entra en este sitio web.<\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfPara qu\u00e9 utilizamos sus datos?<\/span> <span style=\"color: var(--wd-text-color); font-size: 14px;\"><br>\nParte de los datos se recogen para garantizar un funcionamiento sin errores del sitio web. Otros datos pueden utilizarse para analizar su comportamiento como usuario.<\/span><\/p>\n<p><span style=\"text-decoration: underline;\">\u00bfQu\u00e9 derechos tiene en relaci\u00f3n con sus datos? <\/span><br>\nTiene derecho a recibir en cualquier momento informaci\u00f3n gratuita sobre el origen, el destinatario y la finalidad de sus datos personales almacenados. Tambi\u00e9n tiene derecho a solicitar la correcci\u00f3n o supresi\u00f3n de estos datos. Si ha dado su consentimiento al tratamiento de datos, puede revocarlo en cualquier momento para el futuro. Tambi\u00e9n tiene derecho a solicitar la limitaci\u00f3n del tratamiento de sus datos personales en determinadas circunstancias. Adem\u00e1s, tiene derecho a presentar una reclamaci\u00f3n ante la autoridad de control competente.&nbsp;<span style=\"font-size: 14px; color: var(--wd-text-color);\">Puede ponerse en contacto con nosotros en cualquier momento en relaci\u00f3n con esta y otras cuestiones sobre el tema de la protecci\u00f3n de datos.<\/span><\/p>\n<p><b>Herramientas y herramientas de an\u00e1lisis de terceros&nbsp;<\/b><span style=\"color: var(--wd-text-color); font-size: 14px;\"><br>\nAl visitar este sitio web, su comportamiento de navegaci\u00f3n puede ser analizado estad\u00edsticamente. Esto se realiza principalmente con los llamados programas de an\u00e1lisis. Encontrar\u00e1 informaci\u00f3n detallada sobre estos programas de an\u00e1lisis en la siguiente declaraci\u00f3n de protecci\u00f3n de datos.<\/span><\/p>\n<p><b>2. <\/b><b>Notas generales e informaci\u00f3n obligatoria<\/b><p>\n<b>Protecci\u00f3n de datos<\/b><br>\nLos operadores de estas p\u00e1ginas se toman muy en serio la protecci\u00f3n de sus datos personales. Tratamos sus datos personales de forma confidencial y de conformidad con las disposiciones legales sobre protecci\u00f3n de datos y la presente declaraci\u00f3n de protecci\u00f3n de datos.<br>\nCuando usted utiliza este sitio web, se recogen diversos datos personales. Los datos personales son datos que pueden utilizarse para identificarle personalmente. Esta pol\u00edtica de privacidad explica qu\u00e9 datos recogemos y para qu\u00e9 los utilizamos. Tambi\u00e9n explica c\u00f3mo y con qu\u00e9 fin lo hacemos.<br>Queremos se\u00f1alar que la transmisi\u00f3n de datos en Internet (por ejemplo, la comunicaci\u00f3n por correo electr\u00f3nico) puede presentar lagunas de seguridad. No es posible una protecci\u00f3n completa de los datos contra el acceso de terceros.\n<br><br><b>Nota sobre el organismo responsable<\/b><br>El responsable del tratamiento de datos de este sitio web es:<br>Iduna Health &amp; Beauty GmbH\n<br>Jard\u00edn de Becker 11\n<br>53179 Bonn\n<br>Correo electr\u00f3nico: support@fashion-wall.de\n<p>No tenemos obligaci\u00f3n legal de nombrar a un responsable de la protecci\u00f3n de datos. Un responsable del tratamiento de datos es la persona f\u00edsica o jur\u00eddica que, sola o conjuntamente con otras, determina los fines y medios del tratamiento de datos personales (por ejemplo, nombres, direcciones de correo electr\u00f3nico, etc.).<\/p>\n<br><b>Periodo de almacenamiento <\/b> <br>A menos que se haya especificado un periodo de almacenamiento m\u00e1s concreto en esta pol\u00edtica de privacidad, sus datos personales permanecer\u00e1n con nosotros hasta que deje de aplicarse el prop\u00f3sito para el que fueron procesados. Si hace valer una solicitud justificada de supresi\u00f3n o revoca su consentimiento para el tratamiento de datos, sus datos se suprimir\u00e1n, a menos que tengamos otros motivos legalmente admisibles para almacenar sus datos personales (por ejemplo, periodos de conservaci\u00f3n en virtud de la legislaci\u00f3n fiscal o mercantil); en este \u00faltimo caso, los datos se suprimir\u00e1n cuando dejen de aplicarse dichos motivos.\n<br><br><b>Informaci\u00f3n general sobre la base jur\u00eddica del tratamiento de datos en este sitio web <\/b>\n<br>Si ha dado su consentimiento para el tratamiento de datos, tratamos sus datos personales sobre la base del art. 6, apdo. 1 lit. a DSGVO o del art. 9, apdo. 2 lit. a DSGVO si se tratan categor\u00edas especiales de datos de conformidad con el art. 9, apdo. 1 DSGVO. En caso de consentimiento expreso para la transferencia de datos personales a terceros pa\u00edses, el tratamiento de datos tambi\u00e9n se lleva a cabo sobre la base del Art. 49 (1) a DSGVO. Si ha dado su consentimiento para el almacenamiento de cookies o para el acceso a informaci\u00f3n en su dispositivo terminal (por ejemplo, a trav\u00e9s de la huella digital del dispositivo), el tratamiento de datos se lleva a cabo adicionalmente sobre la base del art\u00edculo 25 (1) TTDSG. Este consentimiento puede revocarse en cualquier momento. Si sus datos son necesarios para la ejecuci\u00f3n de un contrato o para la aplicaci\u00f3n de medidas precontractuales, procesamos sus datos sobre la base del art\u00edculo 6, apartado 1, letra b del DSGVO. Adem\u00e1s, si sus datos son necesarios para el cumplimiento de una obligaci\u00f3n legal, los procesamos sobre la base del Art. 6 para. 1 lit. c DSGVO. Adem\u00e1s, el tratamiento de datos puede llevarse a cabo sobre la base de nuestro inter\u00e9s leg\u00edtimo de conformidad con el art. 6, apdo. 1 lit. f DSGVO. En los p\u00e1rrafos siguientes de esta declaraci\u00f3n de protecci\u00f3n de datos se facilita informaci\u00f3n sobre la base jur\u00eddica pertinente en cada caso concreto.\n<br><br><b>Destinatarios de los datos personales <\/b>\n<p>En el curso de nuestras actividades empresariales, cooperamos con diversos organismos externos. En algunos casos, esto tambi\u00e9n requiere la transferencia de datos personales a estos organismos externos. S\u00f3lo revelamos datos personales a organismos externos si es necesario en el contexto de la ejecuci\u00f3n de un contrato, si estamos legalmente obligados a hacerlo (por ejemplo, revelaci\u00f3n de datos a las autoridades fiscales), si tenemos un inter\u00e9s leg\u00edtimo en la revelaci\u00f3n de conformidad con el art. 6 (1) lit. f DSGVO o si otra base jur\u00eddica permite la revelaci\u00f3n de datos. Cuando utilizamos procesadores, s\u00f3lo revelamos datos personales de nuestros clientes sobre la base de un contrato v\u00e1lido sobre el procesamiento encargado. En caso de tratamiento conjunto, se celebra un contrato de tratamiento conjunto.\n<br><br><b>Revocaci\u00f3n de su consentimiento para el tratamiento de datos <\/b><br>Muchas operaciones de tratamiento de datos s\u00f3lo son posibles con su consentimiento expreso. Puede revocar el consentimiento que ya ha dado en cualquier momento. La legalidad del tratamiento de datos efectuado hasta la revocaci\u00f3n no se ver\u00e1 afectada por \u00e9sta.\n<br><br><b>Derecho a oponerse a la recogida de datos en casos espec\u00edficos y a la mercadotecnia directa (Art. 21 GDPR) <\/b>\n<br>SI EL TRATAMIENTO DE DATOS SE BASA EN EL ART. 6 ABS. 1 LIT. E O F DSGVO, TIENE DERECHO A OPONERSE EN CUALQUIER MOMENTO AL TRATAMIENTO DE SUS DATOS PERSONALES POR MOTIVOS DERIVADOS DE SU SITUACI\u00d3N PARTICULAR; ESTO TAMBI\u00c9N SE APLICA A LA ELABORACI\u00d3N DE PERFILES BASADA EN ESTAS DISPOSICIONES. LA BASE JUR\u00cdDICA RESPECTIVA EN LA QUE SE BASA EL TRATAMIENTO SE ENCUENTRA EN ESTA DECLARACI\u00d3N DE PROTECCI\u00d3N DE DATOS. SI SE OPONE, DEJAREMOS DE TRATAR SUS DATOS PERSONALES, A MENOS QUE PODAMOS DEMOSTRAR MOTIVOS LEG\u00cdTIMOS IMPERIOSOS PARA EL TRATAMIENTO QUE PREVALEZCAN SOBRE SUS INTERESES, DERECHOS Y LIBERTADES, O QUE EL TRATAMIENTO SIRVA PARA HACER VALER, EJERCER O DEFENDER RECLAMACIONES LEGALES (OPOSICI\u00d3N EN VIRTUD DEL ART\u00cdCULO 21, APARTADO 1, DE LA LEY DE PROTECCI\u00d3N DE DATOS).\n<br>SI SUS DATOS PERSONALES SE TRATAN CON FINES DE MERCADOTECNIA DIRECTA, TIENE DERECHO A OPONERSE EN CUALQUIER MOMENTO AL TRATAMIENTO DE LOS DATOS PERSONALES QUE LE CONCIERNEN CON FINES DE DICHA MERCADOTECNIA; ESTO TAMBI\u00c9N SE APLICA A LA ELABORACI\u00d3N DE PERFILES EN LA MEDIDA EN QUE EST\u00c9 RELACIONADA CON DICHA MERCADOTECNIA DIRECTA. SI SE OPONE, SUS DATOS PERSONALES DEJAR\u00c1N DE UTILIZARSE POSTERIORMENTE PARA FINES DE MERCADOTECNIA DIRECTA (OPOSICI\u00d3N CON ARREGLO AL ART. 21, APARTADO 2 DE LA DSGVO).\n<br><br><b>Derecho de recurso ante la autoridad de control competente <\/b><br>En caso de infracci\u00f3n del RGPD, los interesados tendr\u00e1n derecho a presentar una reclamaci\u00f3n ante una autoridad de control, en particular en el Estado miembro de su residencia habitual, su lugar de trabajo o el lugar de la presunta infracci\u00f3n. El derecho de recurso se entiende sin perjuicio de cualquier otro recurso administrativo o judicial.\n<br><br><b>Derecho a la portabilidad de los datos <\/b>\n<br>Usted tiene derecho a que los datos que tratamos autom\u00e1ticamente sobre la base de su consentimiento o en cumplimiento de un contrato le sean entregados a usted o a un tercero en un formato com\u00fan legible por m\u00e1quina. Si solicita la transferencia directa de los datos a otro responsable del tratamiento, s\u00f3lo se har\u00e1 en la medida en que sea t\u00e9cnicamente viable.\n<p><b>Informaci\u00f3n, rectificaci\u00f3n y supresi\u00f3n <\/b><br>En el marco de las disposiciones legales aplicables, usted tiene derecho en todo momento a recibir informaci\u00f3n gratuita sobre sus datos personales almacenados, su origen y destinatario y la finalidad del tratamiento de datos y, en su caso, derecho a la rectificaci\u00f3n o supresi\u00f3n de estos datos. Puede ponerse en contacto con nosotros en cualquier momento para este fin y para otras cuestiones sobre el tema de los datos personales.<\/p>\n<p><b>Derecho a restringir el tratamiento <\/b>\n<br>Tiene derecho a solicitar la limitaci\u00f3n del tratamiento de sus datos personales. Para ello, puede ponerse en contacto con nosotros en cualquier momento. El derecho a la restricci\u00f3n del tratamiento existe en los siguientes casos:\n<li>Si impugna la exactitud de sus datos personales almacenados por nosotros, normalmente necesitamos tiempo para comprobarlo. Mientras dure la comprobaci\u00f3n, tiene derecho a solicitar la restricci\u00f3n del tratamiento de sus datos personales.<\/li>\n<li>Si el tratamiento de sus datos personales se ha producido o se est\u00e1 produciendo de forma il\u00edcita, puede solicitar la limitaci\u00f3n del tratamiento de datos en lugar de su supresi\u00f3n.<\/li>\n<li>Si ya no necesitamos sus datos personales, pero usted los necesita para ejercer, defender o hacer valer reclamaciones legales, tiene derecho a solicitar la restricci\u00f3n del tratamiento de sus datos personales en lugar de su supresi\u00f3n.<\/li>\n<li>Si ha presentado una objeci\u00f3n con arreglo al art\u00edculo 21, apartado 1, de la DSGVO, deber\u00e1 llevarse a cabo una ponderaci\u00f3n de sus intereses y los nuestros. Mientras no se haya determinado qu\u00e9 intereses prevalecen, usted tiene derecho a exigir la limitaci\u00f3n del tratamiento de sus datos personales.<\/li>\n<p>Si ha restringido el tratamiento de sus datos personales, dichos datos, adem\u00e1s de almacenarse, s\u00f3lo podr\u00e1n tratarse con su consentimiento o para el reconocimiento, ejercicio o defensa de un derecho en un procedimiento judicial o para la protecci\u00f3n de los derechos de otra persona f\u00edsica o jur\u00eddica o por razones de inter\u00e9s p\u00fablico importantes de la Uni\u00f3n Europea o de un Estado miembro.<\/p>\n<p><b>Cifrado SSL o TLS <\/b>\n<br>Por razones de seguridad y para proteger la transmisi\u00f3n de contenidos confidenciales, como pedidos o consultas que nos env\u00ede como operador del sitio, este sitio utiliza cifrado SSL o TLS. Puede reconocer una conexi\u00f3n cifrada por el hecho de que la l\u00ednea de direcci\u00f3n del navegador cambia de \"http:\/\/\" a \"https:\/\/\" y por el s\u00edmbolo del candado en la l\u00ednea de su navegador.\n<br>Si el cifrado SSL o TLS est\u00e1 activado, los datos que nos transmita no podr\u00e1n ser le\u00eddos por terceros.\n<p><b>Transacciones de pago encriptadas en el sitio web<\/b>\n<br>Si, tras la celebraci\u00f3n de un contrato con costes, existe la obligaci\u00f3n de facilitarnos sus datos de pago (por ejemplo, el n\u00famero de cuenta en caso de autorizaci\u00f3n de domiciliaci\u00f3n bancaria), estos datos son necesarios para la tramitaci\u00f3n de los pagos.<br>\nLas operaciones de pago a trav\u00e9s de los medios de pago habituales (Visa\/MasterCard, domiciliaci\u00f3n bancaria) se realizan exclusivamente a trav\u00e9s de una conexi\u00f3n cifrada SSL o TLS. Puede reconocer una conexi\u00f3n cifrada por el hecho de que la l\u00ednea de direcci\u00f3n del navegador cambia de \"http:\/\/\" a \"https:\/\/\" y por el s\u00edmbolo del candado en la l\u00ednea de su navegador.<br>\nCon la comunicaci\u00f3n cifrada, los datos de pago que nos transmita no podr\u00e1n ser le\u00eddos por terceros.\n<p><b>Objeci\u00f3n a los correos electr\u00f3nicos publicitarios<\/b>\n<br>Queda prohibido el uso de los datos de contacto publicados en el marco de la obligaci\u00f3n de pie de imprenta para el env\u00edo de material publicitario e informativo que no haya sido expresamente solicitado. Los operadores de las p\u00e1ginas se reservan expresamente el derecho a emprender acciones legales en caso de env\u00edo no solicitado de informaci\u00f3n publicitaria, como correos electr\u00f3nicos basura.<\/p>\n<p><strong>3. recogida de datos en este sitio web<\/strong><\/p>\n<p>Al visitar el sitio web\n<br>Cada vez que accede a nuestro sitio web, el navegador de Internet de su dispositivo final env\u00eda autom\u00e1ticamente informaci\u00f3n al servidor de nuestro sitio web, que la almacena temporalmente en archivos de registro, los denominados archivos de registro. Los registros de datos almacenados en este proceso contienen los siguientes datos, que se guardan hasta su eliminaci\u00f3n autom\u00e1tica, por ejemplo, direcci\u00f3n IP, fecha y hora de acceso, nombre de la p\u00e1gina a la que se accede, nombre y URL del archivo al que se accede, URL de referencia (sitio web desde el que se accede), la cantidad de datos transferidos, el tiempo de carga, el navegador utilizado y, si procede, el sistema operativo de su ordenador, as\u00ed como el nombre de su proveedor de acceso.\n<br>La base jur\u00eddica para el tratamiento de datos es el art\u00edculo 6, apartado 1, letra f) DSGVO\/Art. 6(1) p. 1 lit. f DSGVO. Los datos antes mencionados son procesados por nosotros para los siguientes fines: <li>Garantizar el establecimiento de la conexi\u00f3n sin problemas,<\/li>\n<li>Garantizar un uso c\u00f3modo de nuestro sitio web,<\/li>\n<li>Evaluaci\u00f3n de la seguridad y estabilidad del sistema<\/li>\n<li>para otros fines administrativos.<\/li>\n<p>La informaci\u00f3n se almacena y se suprime autom\u00e1ticamente una vez cumplidos los fines mencionados. Los plazos est\u00e1ndar para la supresi\u00f3n se basan en el criterio de necesidad. Adem\u00e1s, puede utilizar diversos servicios del sitio web en los que se tratan otros datos personales y no personales.\n<p><b>Alojamiento<\/b>\n<br>Alojamos el contenido de nuestro sitio web con el siguiente proveedor: Strato AG, Otto-Ostrowski-Stra\u00dfe 7, 10249 Berl\u00edn (en adelante, \"Strato\"). Cuando visita nuestro sitio web, Strato recopila varios archivos de registro, incluidas sus direcciones IP.\n<br>Para m\u00e1s informaci\u00f3n, consulte la pol\u00edtica de privacidad de Strato: https:\/\/www.strato.de\/datenschutz\/.\n<br>El uso de Strato se basa en el art. 6 p\u00e1rr. 1 lit. f DSGVO. Tenemos un inter\u00e9s leg\u00edtimo en la presentaci\u00f3n m\u00e1s fiable de nuestro sitio web. Si se ha solicitado el correspondiente consentimiento, el tratamiento se lleva a cabo exclusivamente sobre la base del art. 6, apdo. 1 lit. a DSGVO y del art. 25, apdo. 1 TTDSG, en la medida en que el consentimiento incluya el almacenamiento de cookies o el acceso a informaci\u00f3n en el dispositivo terminal del usuario (por ejemplo, huella digital del dispositivo), tal como se define en la TTDSG. El consentimiento puede revocarse en cualquier momento.\n<br>Hemos celebrado un contrato de tramitaci\u00f3n de pedidos (AVV) para el uso del servicio mencionado. Se trata de un contrato exigido por la ley de protecci\u00f3n de datos, que garantiza que este servicio solo procesa los datos personales de los visitantes de nuestro sitio web de acuerdo con nuestras instrucciones y en cumplimiento del GDPR.\n<p><b>Cookies<\/b>\n<br>Nuestras p\u00e1ginas de Internet utilizan las llamadas \"cookies\". Las cookies son peque\u00f1os paquetes de datos que no causan ning\u00fan da\u00f1o a su dispositivo final. Se almacenan temporalmente durante una sesi\u00f3n (cookies de sesi\u00f3n) o permanentemente (cookies permanentes) en su dispositivo. Las cookies de sesi\u00f3n se eliminan autom\u00e1ticamente al final de su visita. Las cookies permanentes permanecen almacenadas en su dispositivo hasta que usted las borra o hasta que su navegador las borra autom\u00e1ticamente.\n<br>Las cookies pueden proceder de nosotros (cookies de origen) o de terceras empresas (las denominadas cookies de terceros). Las cookies de terceros permiten integrar determinados servicios de terceras empresas en los sitios web (por ejemplo, cookies para procesar servicios de pago).\n<br>Las cookies tienen diversas funciones. Muchas cookies son t\u00e9cnicamente necesarias, ya que determinadas funciones del sitio web no funcionar\u00edan sin ellas (por ejemplo, la funci\u00f3n de cesta de la compra o la visualizaci\u00f3n de v\u00eddeos). Otras cookies pueden utilizarse para evaluar el comportamiento de los usuarios o con fines publicitarios.\n<br>Las cookies que son necesarias para llevar a cabo el proceso de comunicaci\u00f3n electr\u00f3nica, para proporcionar ciertas funciones que usted ha solicitado (por ejemplo, para la funci\u00f3n de cesta de la compra) o para optimizar el sitio web (por ejemplo, cookies para medir la audiencia web) (cookies necesarias) se almacenan sobre la base del art. 6 (1) lit. f DSGVO, a menos que se especifique otra base legal. El operador del sitio web tiene un inter\u00e9s leg\u00edtimo en almacenar cookies necesarias para la prestaci\u00f3n t\u00e9cnicamente sin errores y optimizada de sus servicios. En la medida en que se haya solicitado el consentimiento para el almacenamiento de cookies y tecnolog\u00edas de reconocimiento comparables, el procesamiento se lleva a cabo exclusivamente sobre la base de este consentimiento (art. 6, apdo. 1 lit. a DSGVO y art. 25, apdo. 1 TTDSG); el consentimiento puede revocarse en cualquier momento.\n<br>Puede configurar su navegador para que le informe sobre la instalaci\u00f3n de cookies y permitirlas s\u00f3lo en casos individuales, excluir la aceptaci\u00f3n de cookies para determinados casos o en general y activar la eliminaci\u00f3n autom\u00e1tica de cookies al cerrar el navegador. Si desactiva las cookies, la funcionalidad de este sitio web puede verse limitada.\n<br>Puede consultar qu\u00e9 cookies y servicios se utilizan en este sitio web en esta pol\u00edtica de privacidad.\n<p><b>Formulario de contacto<\/b>\n<br>Si nos env\u00eda consultas a trav\u00e9s del formulario de contacto, sus datos del formulario de consulta, incluidos los datos de contacto que nos facilite en \u00e9l, ser\u00e1n almacenados por nosotros con el fin de tramitar la consulta y en caso de preguntas de seguimiento. No transmitimos estos datos sin su consentimiento.\n<br>El tratamiento de estos datos se basa en el art. 6 (1) lit. b DSGVO si su solicitud est\u00e1 relacionada con la ejecuci\u00f3n de un contrato o es necesaria para la aplicaci\u00f3n de medidas precontractuales. En todos los dem\u00e1s casos, el tratamiento se basa en nuestro inter\u00e9s leg\u00edtimo en la tramitaci\u00f3n efectiva de las consultas que se nos dirigen (art. 6 (1) (f) DSGVO) o en su consentimiento (art. 6 (1) (a) DSGVO) si as\u00ed se ha solicitado; el consentimiento puede revocarse en cualquier momento.\n<br>Los datos que introduzca en el formulario de contacto permanecer\u00e1n con nosotros hasta que nos solicite que los eliminemos, revoque su consentimiento para almacenarlos o deje de aplicarse el prop\u00f3sito para el que fueron almacenados (por ejemplo, despu\u00e9s de que hayamos terminado de procesar su consulta). Las disposiciones legales obligatorias, en particular los periodos de conservaci\u00f3n, no se ver\u00e1n afectadas.<\/p>\n<p><b>Solicitud por correo electr\u00f3nico, tel\u00e9fono o fax <\/b>\n<br>Si se pone en contacto con nosotros por correo electr\u00f3nico, tel\u00e9fono o fax, su consulta, incluidos todos los datos personales resultantes (nombre, consulta), ser\u00e1 almacenada y procesada por nosotros con el fin de tramitar su solicitud. No transmitiremos estos datos sin su consentimiento.\n<br>El tratamiento de estos datos se basa en el art. 6 (1) lit. b DSGVO si su solicitud est\u00e1 relacionada con la ejecuci\u00f3n de un contrato o es necesaria para la aplicaci\u00f3n de medidas precontractuales. En todos los dem\u00e1s casos, el tratamiento se basa en nuestro inter\u00e9s leg\u00edtimo en la tramitaci\u00f3n efectiva de las consultas que se nos dirigen (art. 6 (1) (f) DSGVO) o en su consentimiento (art. 6 (1) (a) DSGVO) si as\u00ed se ha solicitado; el consentimiento puede revocarse en cualquier momento.\n<br>Los datos que nos env\u00ede a trav\u00e9s de las solicitudes de contacto permanecer\u00e1n con nosotros hasta que nos solicite que los eliminemos, revoque su consentimiento para almacenarlos o deje de aplicarse el prop\u00f3sito para el que se almacenaron (por ejemplo, despu\u00e9s de que hayamos finalizado la tramitaci\u00f3n de su solicitud). Las disposiciones legales obligatorias, en particular los plazos legales de conservaci\u00f3n, no se ver\u00e1n afectadas.<\/p>\n<p><b>Si realiza el pedido a trav\u00e9s de nuestro sitio web<\/b>\n<br>Puede realizar pedidos a trav\u00e9s de nuestro sitio web como invitado sin registrarse o registrarse en nuestra tienda como cliente para futuros pedidos. La ventaja de registrarse es que puede acceder directamente a nuestra tienda con su direcci\u00f3n de correo electr\u00f3nico y contrase\u00f1a en caso de un futuro pedido sin tener que volver a introducir sus datos de contacto.\n<br>Sus datos personales se introducen en una m\u00e1scara de entrada, se nos transmiten y se almacenan. Si realiza un pedido a trav\u00e9s de nuestro sitio web, primero recopilamos los siguientes datos tanto en el caso de un pedido de invitado como en el caso de registro en la tienda:\n<li>Saludo, nombre, apellido,<\/li>\n<li>una direcci\u00f3n de correo electr\u00f3nico v\u00e1lida,<\/li>\n<li>Direcci\u00f3n,<\/li>\n<li>N\u00famero de tel\u00e9fono (fijo y\/o m\u00f3vil)<\/li>\n<p>La recogida de estos datos se lleva a cabo,<\/p>\n<li>para poder identificarle como nuestro cliente;<\/li>\n<li>para poder procesar, cumplir y gestionar su pedido;<\/li>\n<li>para la correspondencia con usted;<\/li>\n<li>para la facturaci\u00f3n;<\/li>\n<li>para la liquidaci\u00f3n de cualquier reclamaci\u00f3n de responsabilidad civil existente, as\u00ed como para la presentaci\u00f3n de cualquier reclamaci\u00f3n contra usted;<\/li>\n<li>garantizar la administraci\u00f3n t\u00e9cnica de nuestro sitio web;<\/li>\n<li>para gestionar los datos de nuestros clientes.<\/li>\n<br>Como parte del proceso de pedido, se obtiene su consentimiento para el tratamiento de estos datos.\n<br>El tratamiento de datos se lleva a cabo en respuesta a su pedido y\/o registro y es necesario de conformidad con el art. 6 p\u00e1rr. 1 p. 1 lit. b DSGVO para los fines antes mencionados para la tramitaci\u00f3n adecuada de su pedido y para el cumplimiento mutuo de las obligaciones derivadas del contrato de compra.\n<br>Los datos personales recopilados por nosotros para la tramitaci\u00f3n de su pedido se almacenar\u00e1n hasta la expiraci\u00f3n de la obligaci\u00f3n legal de almacenamiento y, a continuaci\u00f3n, se eliminar\u00e1n, a menos que estemos obligados a almacenar los datos durante un per\u00edodo m\u00e1s largo de conformidad con el art\u00edculo 6 (1) frase 1 lit. c DSGVO debido a las obligaciones de almacenamiento y documentaci\u00f3n de la legislaci\u00f3n fiscal y comercial (de HGB, StGB o AO) o usted haya dado su consentimiento para el almacenamiento m\u00e1s all\u00e1 de esto de conformidad con el art\u00edculo 6 (1) frase 1 lit. a DSGVO.\n<br><br>S\u00f3lo transmitimos datos personales a terceros si es necesario en el marco de la tramitaci\u00f3n del contrato, por ejemplo a las empresas encargadas de la entrega de la mercanc\u00eda o a la entidad de cr\u00e9dito encargada de la tramitaci\u00f3n del pago. La transmisi\u00f3n ulterior de los datos no tiene lugar o s\u00f3lo tiene lugar si usted ha dado su consentimiento expreso a la transmisi\u00f3n. Sus datos no se transmitir\u00e1n a terceros sin su consentimiento expreso, por ejemplo con fines publicitarios.\n<br>La base para el tratamiento de datos es el art. 6 p\u00e1rr. 1 lit. b DSGVO, que permite el tratamiento de datos para el cumplimiento de un contrato o de medidas precontractuales.<\/p>\n<p><b>Proveedores externos de servicios de pago<\/b>\n<br>Utilizamos proveedores externos de servicios de pago a trav\u00e9s de cuyas plataformas los usuarios y nosotros podemos realizar transacciones de pago (por ejemplo, cada uno con un enlace a la declaraci\u00f3n de protecci\u00f3n de datos, Paypal (https:\/\/www.paypal.com\/de\/webapps\/mpp\/ua\/privacy-full), Klarna (https:\/\/www.klarna.com\/de\/datenschutz\/), Giropay (https:\/\/www.giropay.de\/rechtliches\/datenschutz-agb\/), Visa (https:\/\/www.visa.de\/datenschutz), Mastercard (https:\/\/www.mastercard.de\/de-de\/datenschutz.html), American Express (https:\/\/www.americanexpress.com\/de\/content\/privacy-policy-statement.html)\n<br>En el marco del cumplimiento de contratos, utilizamos los proveedores de servicios de pago sobre la base del art. 6 p\u00e1rr. 1 lit. b. DSGVO. Adem\u00e1s, utilizamos proveedores de servicios de pago externos sobre la base de nuestros intereses leg\u00edtimos de conformidad con el art. 6, apdo. 1 lit. b. DSGVO con el fin de ofrecer a nuestros usuarios opciones de pago eficaces y seguras.\n<br>Los datos procesados por los proveedores de servicios de pago incluyen datos de inventario, como el nombre y la direcci\u00f3n, datos bancarios, como n\u00fameros de cuenta o de tarjeta de cr\u00e9dito, contrase\u00f1as, TAN y sumas de comprobaci\u00f3n, as\u00ed como el contrato, totales e informaci\u00f3n relacionada con el destinatario. Estos datos son necesarios para realizar las transacciones. Sin embargo, los datos introducidos s\u00f3lo son procesados por los proveedores de servicios de pago y almacenados con ellos. Es decir, no recibimos ninguna informaci\u00f3n relacionada con la cuenta o la tarjeta de cr\u00e9dito, sino s\u00f3lo informaci\u00f3n con la confirmaci\u00f3n o informaci\u00f3n negativa del pago. En determinadas circunstancias, los proveedores de servicios de pago pueden transmitir los datos a agencias de cr\u00e9dito. La finalidad de esta transmisi\u00f3n es comprobar la identidad y la solvencia. Consulte las condiciones y la informaci\u00f3n sobre protecci\u00f3n de datos de los proveedores de servicios de pago.\n<br>Las condiciones y avisos sobre protecci\u00f3n de datos de los respectivos proveedores de servicios de pago se aplican a las operaciones de pago y pueden consultarse en los respectivos sitios web o aplicaciones de operaciones. Tambi\u00e9n nos remitimos a ellos para obtener m\u00e1s informaci\u00f3n y hacer valer los derechos de revocaci\u00f3n, informaci\u00f3n y otros derechos de los interesados.<\/p>\n<p><b>Proveedores externos de servicios de transporte<\/b><br>\nSi nos ha dado su consentimiento expreso para ello durante o despu\u00e9s de su pedido, transmitiremos su direcci\u00f3n de correo electr\u00f3nico y n\u00famero de tel\u00e9fono al proveedor de servicios de env\u00edo seleccionado sobre la base de este consentimiento de conformidad con el art. 6 (1) frase 1 lit. a DSGVO para que el proveedor de servicios de env\u00edo pueda ponerse en contacto con usted antes de la entrega a efectos de notificaci\u00f3n o coordinaci\u00f3n de la entrega.<br>\nEl consentimiento puede revocarse en cualquier momento enviando un mensaje a la opci\u00f3n de contacto descrita a continuaci\u00f3n o directamente al proveedor de servicios de env\u00edo a la direcci\u00f3n de contacto indicada m\u00e1s abajo. Tras la revocaci\u00f3n, eliminaremos sus datos facilitados para este fin, a menos que haya consentido expresamente un uso posterior de sus datos o que nos reservemos el derecho a utilizar datos m\u00e1s all\u00e1 de esto, lo cual est\u00e1 permitido por la ley y sobre lo cual le informamos en esta declaraci\u00f3n.<br>\nDHL Parcel GmbH<br>\nStr\u00e4\u00dfchensweg 10<br>\n53113 Bonn<br>\nTel\u00e9fono: +49 (0) 228 \/ 1820\n<br>Correo electr\u00f3nico: <a href=\"mailto:impressum.paket@dhl.com\">impressum.paket@dhl.com<\/a>\n<br><a href=\"https:\/\/www.dhl.de\/datenschutz\">https:\/\/www.dhl.de\/datenschutz<\/a><\/p>\n<p><strong>4. redes sociales<\/strong><\/p>\n<p><b>Instagram <\/b>\n<br>En este sitio web se integran funciones del servicio Instagram. Estas funciones son ofrecidas por Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dubl\u00edn 2, Irlanda.\n<br>Cuando el elemento de redes sociales est\u00e1 activo, se establece una conexi\u00f3n directa entre su dispositivo final y el servidor de Instagram. De este modo, Instagram recibe informaci\u00f3n sobre su visita a este sitio web.\n<br>Si ha iniciado sesi\u00f3n en su cuenta de Instagram, puede vincular el contenido de este sitio web a su perfil de Instagram haciendo clic en el bot\u00f3n de Instagram. Esto permite a Instagram asociar su visita a este sitio web con su cuenta de usuario. Nos gustar\u00eda se\u00f1alar que nosotros, como proveedores de las p\u00e1ginas, no tenemos conocimiento del contenido de los datos transmitidos ni de su uso por parte de Instagram.\n<br>En la medida en que se haya obtenido el consentimiento, el servicio arriba mencionado se utiliza sobre la base del art. 6 p\u00e1rr. 1 lit. a DSGVO y del art. 25 TTDSG. El consentimiento puede revocarse en cualquier momento. En la medida en que no se haya obtenido el consentimiento, el uso del servicio se basa en nuestro inter\u00e9s leg\u00edtimo en lograr la mayor visibilidad posible en los medios sociales.\n<br>En la medida en que en nuestro sitio web se recojan datos personales con ayuda de la herramienta aqu\u00ed descrita y se transmitan a Facebook o Instagram, nosotros y Meta Platforms Ireland Limited, 4 Grand Canal Square, Grand Canal Harbour, Dubl\u00edn 2, Irlanda, seremos corresponsables de este tratamiento de datos (art. 26 DSGVO). La responsabilidad conjunta se limita exclusivamente a la recogida de los datos y su env\u00edo a Facebook o Instagram. El tratamiento por parte de Facebook o Instagram que tiene lugar despu\u00e9s del env\u00edo no forma parte de la responsabilidad conjunta. Nuestras obligaciones conjuntas se han establecido en un acuerdo de tratamiento conjunto. El texto del acuerdo puede consultarse en: https:\/\/www.facebook.com\/legal\/controller_addendum. Seg\u00fan este acuerdo, somos responsables de proporcionar la informaci\u00f3n sobre protecci\u00f3n de datos al utilizar la herramienta de Facebook o Instagram y de la implementaci\u00f3n segura de la protecci\u00f3n de datos de la herramienta en nuestro sitio web. Facebook es responsable de la seguridad de los datos de los productos de Facebook e Instagram.<br> Puedes hacer valer los derechos de los interesados (por ejemplo, solicitudes de informaci\u00f3n) en relaci\u00f3n con los datos procesados por Facebook o Instagram directamente con Facebook. Si haces valer los derechos del interesado ante nosotros, estamos obligados a transmitirlos a Facebook.\n<br>La transferencia de datos a Estados Unidos se basa en las cl\u00e1usulas contractuales tipo de la Comisi\u00f3n Europea. Los detalles pueden encontrarse aqu\u00ed:\nhttps:\/\/www.facebook.com\/legal\/EU_data_transfer_addendum, https:\/\/help.instagram.com\/519522125107875 y https:\/\/de-de.facebook.com\/help\/566994660333381.\n<br>Para m\u00e1s informaci\u00f3n, consulta la pol\u00edtica de privacidad de Instagram: https:\/\/instagram.com\/about\/legal\/privacy\/.\n<br>La empresa est\u00e1 certificada de acuerdo con el \"Marco de Privacidad de Datos UE-EE.UU.\" (DPF). El DPF es un acuerdo entre la Uni\u00f3n Europea y EE.UU. cuyo objetivo es garantizar el cumplimiento de las normas europeas de protecci\u00f3n de datos en el tratamiento de datos en EE.UU.. Toda empresa certificada conforme al DPF se compromete a cumplir estas normas de protecci\u00f3n de datos. Para m\u00e1s informaci\u00f3n, p\u00f3ngase en contacto con el proveedor en el siguiente enlace: https:\/\/www.dataprivacyframework.gov\/s\/participant-search\/participant- detail?contact=true&amp;id=a2zt0000000GnywAAC&amp;status=Active<\/p>\n<p><strong>5 Bolet\u00edn informativo<\/strong><\/p><b>Datos del bolet\u00edn <\/b>\n<br>Si desea recibir el bolet\u00edn informativo que se ofrece en el sitio web, necesitamos que nos facilite una direcci\u00f3n de correo electr\u00f3nico, as\u00ed como informaci\u00f3n que nos permita verificar que usted es el titular de la direcci\u00f3n de correo electr\u00f3nico especificada y que est\u00e1 de acuerdo en recibir el bolet\u00edn informativo. No se recopilar\u00e1n m\u00e1s datos o s\u00f3lo se recopilar\u00e1n de forma voluntaria. Utilizamos estos datos exclusivamente para enviar la informaci\u00f3n solicitada y no los transmitimos a terceros.\n<br>Los datos introducidos en el formulario de inscripci\u00f3n al bolet\u00edn se procesan exclusivamente sobre la base de su consentimiento (art. 6, apdo. 1 lit. a DSGVO). Puede revocar su consentimiento para el almacenamiento de los datos, la direcci\u00f3n de correo electr\u00f3nico y su uso para el env\u00edo del bolet\u00edn en cualquier momento, por ejemplo a trav\u00e9s del enlace \"darse de baja\" del bolet\u00edn. La legalidad de las operaciones de tratamiento de datos ya realizadas no se ver\u00e1 afectada por la revocaci\u00f3n.\n<br>Los datos que facilite con el fin de recibir el bolet\u00edn ser\u00e1n almacenados por nosotros o por el proveedor de servicios del bolet\u00edn hasta que se d\u00e9 de baja del bolet\u00edn y se eliminar\u00e1n de la lista de distribuci\u00f3n del bolet\u00edn despu\u00e9s de que se d\u00e9 de baja del bolet\u00edn o despu\u00e9s de que el prop\u00f3sito haya dejado de existir. Nos reservamos el derecho a eliminar o bloquear direcciones de correo electr\u00f3nico de nuestra lista de distribuci\u00f3n de boletines a nuestra discreci\u00f3n en el \u00e1mbito de nuestro inter\u00e9s leg\u00edtimo de conformidad con el art. 6 (1) lit. f DSGVO.\n<br>Esto no afecta a los datos que hayamos almacenado para otros fines.\n<br>Despu\u00e9s de darse de baja de la lista de distribuci\u00f3n del bolet\u00edn, su direcci\u00f3n de correo electr\u00f3nico ser\u00e1 almacenada por nosotros o por el proveedor de servicios del bolet\u00edn en una lista negra si es necesario para evitar futuros env\u00edos. Los datos de la lista negra s\u00f3lo se utilizar\u00e1n para este fin y no se fusionar\u00e1n con otros datos. Esto sirve tanto a sus intereses como a nuestros intereses en el cumplimiento de los requisitos legales en el env\u00edo de boletines informativos (inter\u00e9s leg\u00edtimo en el sentido del Art. 6 P\u00e1rr. 1 lit. f DSGVO). El almacenamiento en la lista negra no est\u00e1 limitado en el tiempo. <b>Puede oponerse al almacenamiento si sus intereses prevalecen sobre nuestro inter\u00e9s leg\u00edtimo. <\/b><\/p>\n<p><b>Brevo (antes SendInBlue) GmbH&nbsp;<\/b>\n<br>Puede registrarse para recibir un bolet\u00edn de noticias. Utilizamos el proveedor de servicios de env\u00edo Brevo (antes Sendinblue) GmbH para prestar el servicio. <br>Encontrar\u00e1 informaci\u00f3n sobre la protecci\u00f3n de datos de Brevo en la siguiente p\u00e1gina <a href=\"http:\/\/www.brevo.com\/de\/legal\/privacypolicy\/\"><b>www.brevo.com\/de\/legal\/privacypolicy<\/b><\/a>&nbsp;o bajo Contacto: Brevo GmbH, K\u00f6penicker Stra\u00dfe 126, 10179 Berl\u00edn.<\/p>\n<p><b>Google Analytics<\/b>\n<br>Utilizamos Google Analytics, un servicio de an\u00e1lisis web prestado por Google LLC (\"Google\"), sobre la base de nuestros intereses leg\u00edtimos (es decir, el inter\u00e9s en el an\u00e1lisis, la optimizaci\u00f3n y el funcionamiento econ\u00f3mico de nuestra oferta en l\u00ednea en el sentido del art. 6 (1) lit. f. DSGVO). DSGVO) Google Analytics, un servicio anal\u00edtico de web prestado por Google LLC (\"Google\"). Google utiliza cookies. La informaci\u00f3n generada por la cookie sobre el uso de la oferta en l\u00ednea por parte de los usuarios se transmite normalmente a un servidor de Google en EE.UU. y se almacena all\u00ed.\n<br>Google cuenta con la certificaci\u00f3n del acuerdo Privacy Shield y, por lo tanto, ofrece una garant\u00eda de cumplimiento de la legislaci\u00f3n europea en materia de protecci\u00f3n de datos (https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&amp;status=Active).\n<br>Google usar\u00e1 esta informaci\u00f3n por cuenta nuestra con el prop\u00f3sito de seguir la pista de su uso del website, recopilando informes de la actividad del website y prestando otros servicios relacionados con la actividad del website y el uso de Internet. Al hacerlo, se pueden crear perfiles de usuario seud\u00f3nimos de los usuarios a partir de los datos procesados.\n<br>S\u00f3lo utilizamos Google Analytics con la anonimizaci\u00f3n de IP activada. Esto significa que la direcci\u00f3n IP del usuario es acortada por Google dentro de los estados miembros de la Uni\u00f3n Europea o en otros estados contratantes del Acuerdo sobre el Espacio Econ\u00f3mico Europeo. S\u00f3lo en casos excepcionales se transmitir\u00e1 la direcci\u00f3n IP completa a un servidor de Google en EE.UU. y se acortar\u00e1 all\u00ed.\n<br>La direcci\u00f3n IP transmitida por el navegador del usuario no se fusionar\u00e1 con otros datos de Google. Los usuarios pueden impedir el almacenamiento de cookies configurando el software de su navegador en consecuencia; los usuarios tambi\u00e9n pueden impedir la recopilaci\u00f3n de los datos generados por la cookie y relacionados con su uso de la oferta en l\u00ednea a Google, as\u00ed como el procesamiento de estos datos por parte de Google descargando e instalando el plugin del navegador disponible en el siguiente enlace: http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de.\n<br>Para obtener m\u00e1s informaci\u00f3n sobre el uso que Google hace de los datos, la configuraci\u00f3n y las opciones de inhabilitaci\u00f3n, consulte la pol\u00edtica de privacidad de Google (https:\/\/policies.google.com\/technologies\/ads) y la configuraci\u00f3n para la visualizaci\u00f3n de anuncios por parte de Google (https:\/\/adssettings.google.com\/authenticated).\n<br>Los datos personales de los usuarios se eliminan o se convierten en an\u00f3nimos al cabo de 14 meses.<\/p>\n<p><b>Fuente: <\/b>https:\/\/www.e-recht24.de<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Datenschutzerkl\u00e4rung Datenschutzerkl\u00e4rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzerkl\u00e4rung - Fashion Wall<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fashion-wall.de\/es\/datenschutzerklarung\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Fashion Wall\" \/>\n<meta property=\"og:description\" content=\"Datenschutzerkl\u00e4rung Datenschutzerkl\u00e4rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fashion-wall.de\/es\/datenschutzerklarung\/\" \/>\n<meta property=\"og:site_name\" content=\"Fashion Wall\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T16:27:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/fashion-wall.de\/datenschutzerklarung\/\",\"url\":\"https:\/\/fashion-wall.de\/datenschutzerklarung\/\",\"name\":\"Datenschutzerkl\u00e4rung - Fashion Wall\",\"isPartOf\":{\"@id\":\"https:\/\/fashion-wall.de\/#website\"},\"datePublished\":\"2023-09-10T10:22:00+00:00\",\"dateModified\":\"2023-09-29T16:27:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/fashion-wall.de\/datenschutzerklarung\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/fashion-wall.de\/datenschutzerklarung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/fashion-wall.de\/datenschutzerklarung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/fashion-wall.de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/fashion-wall.de\/#website\",\"url\":\"https:\/\/fashion-wall.de\/\",\"name\":\"Fashion Wall\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/fashion-wall.de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/fashion-wall.de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/fashion-wall.de\/#organization\",\"name\":\"Fashion Wall\",\"url\":\"https:\/\/fashion-wall.de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/fashion-wall.de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/fashion-wall.de\/wp-content\/uploads\/2023\/09\/Logo-Fashion-Wall.png\",\"contentUrl\":\"http:\/\/fashion-wall.de\/wp-content\/uploads\/2023\/09\/Logo-Fashion-Wall.png\",\"width\":851,\"height\":341,\"caption\":\"Fashion Wall\"},\"image\":{\"@id\":\"https:\/\/fashion-wall.de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Fashion Wall","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fashion-wall.de\/es\/datenschutzerklarung\/","og_locale":"es_ES","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Fashion Wall","og_description":"Datenschutzerkl\u00e4rung Datenschutzerkl\u00e4rung 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren","og_url":"https:\/\/fashion-wall.de\/es\/datenschutzerklarung\/","og_site_name":"Fashion Wall","article_modified_time":"2023-09-29T16:27:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fashion-wall.de\/datenschutzerklarung\/","url":"https:\/\/fashion-wall.de\/datenschutzerklarung\/","name":"Datenschutzerkl\u00e4rung - Fashion Wall","isPartOf":{"@id":"https:\/\/fashion-wall.de\/#website"},"datePublished":"2023-09-10T10:22:00+00:00","dateModified":"2023-09-29T16:27:42+00:00","breadcrumb":{"@id":"https:\/\/fashion-wall.de\/datenschutzerklarung\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fashion-wall.de\/datenschutzerklarung\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fashion-wall.de\/datenschutzerklarung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fashion-wall.de\/"},{"@type":"ListItem","position":2,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/fashion-wall.de\/#website","url":"https:\/\/fashion-wall.de\/","name":"Fashion Wall","description":"","publisher":{"@id":"https:\/\/fashion-wall.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fashion-wall.de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/fashion-wall.de\/#organization","name":"Fashion Wall","url":"https:\/\/fashion-wall.de\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/fashion-wall.de\/#\/schema\/logo\/image\/","url":"http:\/\/fashion-wall.de\/wp-content\/uploads\/2023\/09\/Logo-Fashion-Wall.png","contentUrl":"http:\/\/fashion-wall.de\/wp-content\/uploads\/2023\/09\/Logo-Fashion-Wall.png","width":851,"height":341,"caption":"Fashion Wall"},"image":{"@id":"https:\/\/fashion-wall.de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/pages\/15879"}],"collection":[{"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/comments?post=15879"}],"version-history":[{"count":25,"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/pages\/15879\/revisions"}],"predecessor-version":[{"id":16937,"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/pages\/15879\/revisions\/16937"}],"wp:attachment":[{"href":"https:\/\/fashion-wall.de\/es\/wp-json\/wp\/v2\/media?parent=15879"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}